{"id":375,"date":"2023-09-27T15:57:22","date_gmt":"2023-09-27T13:57:22","guid":{"rendered":"https:\/\/aozuerichsee.ch\/?page_id=375"},"modified":"2026-04-11T22:00:12","modified_gmt":"2026-04-11T20:00:12","slug":"proben","status":"publish","type":"page","link":"https:\/\/aozuerichsee.ch\/index.php\/proben\/","title":{"rendered":"Proben"},"content":{"rendered":"\n<div class=\"wp-block-media-text has-media-on-the-right is-stacked-on-mobile is-vertically-aligned-center\" style=\"grid-template-columns:auto 38%\"><div class=\"wp-block-media-text__content\">\n<p class=\"has-text-align-center has-medium-font-size\">\ud83e\ude97 <strong>Machen Sie mit \u2013 Werden Sie Teil des AOZ!<\/strong> <\/p>\n\n\n\n<p class=\"has-text-align-center has-medium-font-size\">Wir proben <strong>jeden Donnerstag<\/strong> (ausser Schulferien)<\/p>\n\n\n\n<p class=\"has-text-align-center has-medium-font-size\">von <strong>19.50 bis 21.30 Uhr<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-center has-medium-font-size\">im <a href=\"https:\/\/maps.app.goo.gl\/p8J3LdMCPLd6twDWA\">Mehrzweckraum des Schulhauses Rotweg in Horgen<\/a><\/p>\n\n\n\n<p class=\"has-text-align-center has-medium-font-size\">Unsere Proben bieten Raum f\u00fcr musikalisches Wachstum und pers\u00f6nliche Begegnungen.<\/p>\n<\/div><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"632\" height=\"1024\" src=\"https:\/\/aozuerichsee.ch\/wp-content\/uploads\/2023\/10\/20231012_080230-632x1024.jpg\" alt=\"\" class=\"wp-image-631 size-full\" srcset=\"https:\/\/aozuerichsee.ch\/wp-content\/uploads\/2023\/10\/20231012_080230-632x1024.jpg 632w, https:\/\/aozuerichsee.ch\/wp-content\/uploads\/2023\/10\/20231012_080230-185x300.jpg 185w, https:\/\/aozuerichsee.ch\/wp-content\/uploads\/2023\/10\/20231012_080230-768x1244.jpg 768w, https:\/\/aozuerichsee.ch\/wp-content\/uploads\/2023\/10\/20231012_080230-948x1536.jpg 948w, https:\/\/aozuerichsee.ch\/wp-content\/uploads\/2023\/10\/20231012_080230-1264x2048.jpg 1264w, https:\/\/aozuerichsee.ch\/wp-content\/uploads\/2023\/10\/20231012_080230-scaled.jpg 1580w\" sizes=\"auto, (max-width: 632px) 100vw, 632px\" \/><\/figure><\/div>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n","protected":false},"excerpt":{"rendered":"<p>\ud83e\ude97 Machen Sie mit \u2013 Werden Sie Teil des AOZ! Wir proben jeden Donnerstag (ausser Schulferien) von 19.50 bis 21.30 Uhr im Mehrzweckraum des Schulhauses Rotweg in Horgen Unsere Proben bieten Raum f\u00fcr musikalisches Wachstum und pers\u00f6nliche Begegnungen.<\/p>\n","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-375","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/aozuerichsee.ch\/index.php\/wp-json\/wp\/v2\/pages\/375","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aozuerichsee.ch\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/aozuerichsee.ch\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/aozuerichsee.ch\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/aozuerichsee.ch\/index.php\/wp-json\/wp\/v2\/comments?post=375"}],"version-history":[{"count":31,"href":"https:\/\/aozuerichsee.ch\/index.php\/wp-json\/wp\/v2\/pages\/375\/revisions"}],"predecessor-version":[{"id":1599,"href":"https:\/\/aozuerichsee.ch\/index.php\/wp-json\/wp\/v2\/pages\/375\/revisions\/1599"}],"wp:attachment":[{"href":"https:\/\/aozuerichsee.ch\/index.php\/wp-json\/wp\/v2\/media?parent=375"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}